{"id":2352,"date":"2023-04-24T13:58:39","date_gmt":"2023-04-24T11:58:39","guid":{"rendered":"https:\/\/www.fondslesbien.org\/?p=2352"},"modified":"2024-05-05T19:01:54","modified_gmt":"2024-05-05T17:01:54","slug":"essai-sur-la-sexualite-lesbienne","status":"publish","type":"post","link":"https:\/\/www.fondslesbien.org\/en\/essai-sur-la-sexualite-lesbienne\/","title":{"rendered":"&#8220;A nos d\u00e9sirs&#8221;, essai sur la sexualit\u00e9 lesbienne"},"content":{"rendered":"<p>La journaliste Elodie Font s&#8217;est fait conna\u00eetre gr\u00e2ce \u00e0 des podcast intimes et dr\u00f4les sur le Coming Out (&#8220;Coming In&#8221;) et la procr\u00e9ation m\u00e9dicalement assist\u00e9e. Elle achevait, au moment du soutien de la LIG, un ouvrage sur la sexualit\u00e9 lesbienne, qui est entretemps sorti sous le titre &#8220;A nos d\u00e9sirs&#8221;, aux \u00e9ditions de la D\u00e9ferlante. C\u2019est un essai sur le d\u00e9sir des femmes et la mani\u00e8re dont il se d\u00e9ploie hors du regard de \u00ab validation \u00bb masculin : comment ce d\u00e9sir est, aux yeux de la soci\u00e9t\u00e9, souvent un non sujet (une sexualit\u00e9 sans p\u00e9n\u00e9tration d\u2019un p\u00e9nis, hein quoi comment ??), comment, en le ressentant, certaines femmes apprennent \u00e0 dire non \u00e0 la norme, non aux injonctions pesant sur leurs corps et oui \u00e0 un amour charnel consenti &#8211; pour une majorit\u00e9 d\u2019entre elles, \u00e9videmment la r\u00e9alit\u00e9 n\u2019est pas aussi rose pour chacune d\u2019entre nous. Plus largement, comment les lesbiennes bouleversent les scripts sexuels \u00e9tablis dans les sch\u00e9mas h\u00e9t\u00e9rosexuels, comment elles en recr\u00e9ent d\u2019autres et comment elles apprennent \u00e0 vivre avec un d\u00e9sir plus ou moins \u00e9loign\u00e9 de la norme ?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La journaliste Elodie Font s&#8217;est fait conna\u00eetre gr\u00e2ce \u00e0 des podcast intimes et dr\u00f4les sur le Coming Out (&#8220;Coming In&#8221;) et la procr\u00e9ation m\u00e9dicalement assist\u00e9e. Elle achevait, au moment du soutien de la LIG, un ouvrage sur la sexualit\u00e9 lesbienne, qui est entretemps sorti sous le titre &#8220;A nos d\u00e9sirs&#8221;, aux \u00e9ditions de la D\u00e9ferlante&#8230;.<\/p>\n","protected":false},"author":2,"featured_media":2353,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-2352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-projets-soutenus"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["fr","en"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;A nos d\u00e9sirs&quot;, essai sur la sexualit\u00e9 lesbienne &#8212; LIG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;A nos d\u00e9sirs&quot;, essai sur la sexualit\u00e9 lesbienne &#8212; LIG\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/\" \/>\n<meta property=\"og:site_name\" content=\"LIG\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-24T11:58:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-05T17:01:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2023\/04\/elodiefont.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"964\" \/>\n\t<meta property=\"og:image:height\" content=\"618\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Veronica Noseda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Veronica Noseda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/\"},\"author\":{\"name\":\"Veronica Noseda\",\"@id\":\"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec\"},\"headline\":\"&#8220;A nos d\u00e9sirs&#8221;, essai sur la sexualit\u00e9 lesbienne\",\"datePublished\":\"2023-04-24T11:58:39+00:00\",\"dateModified\":\"2024-05-05T17:01:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/\"},\"wordCount\":210,\"image\":{\"@id\":\"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2023\/04\/elodiefont.jpg\",\"articleSection\":[\"Projets soutenus\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/\",\"url\":\"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/\",\"name\":\"\\\"A nos d\u00e9sirs\\\", essai sur la sexualit\u00e9 lesbienne &#8212; LIG\",\"isPartOf\":{\"@id\":\"https:\/\/www.fondslesbien.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2023\/04\/elodiefont.jpg\",\"datePublished\":\"2023-04-24T11:58:39+00:00\",\"dateModified\":\"2024-05-05T17:01:54+00:00\",\"author\":{\"@id\":\"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/#primaryimage\",\"url\":\"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2023\/04\/elodiefont.jpg\",\"contentUrl\":\"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2023\/04\/elodiefont.jpg\",\"width\":964,\"height\":618},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fondslesbien.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab\u00a0A nos d\u00e9sirs\u00a0\u00bb, essai sur la sexualit\u00e9 lesbienne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fondslesbien.org\/#website\",\"url\":\"https:\/\/www.fondslesbien.org\/\",\"name\":\"LIG\",\"description\":\"Lesbiennes d\u2019Int\u00e9r\u00eat G\u00e9n\u00e9ral\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fondslesbien.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec\",\"name\":\"Veronica Noseda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.fondslesbien.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/56a20513ad0e9ee8a12ca4e787476caa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/56a20513ad0e9ee8a12ca4e787476caa?s=96&d=mm&r=g\",\"caption\":\"Veronica Noseda\"},\"url\":\"https:\/\/www.fondslesbien.org\/en\/author\/yurilig\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"A nos d\u00e9sirs\", essai sur la sexualit\u00e9 lesbienne &#8212; LIG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/","og_locale":"en_US","og_type":"article","og_title":"\"A nos d\u00e9sirs\", essai sur la sexualit\u00e9 lesbienne &#8212; LIG","og_url":"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/","og_site_name":"LIG","article_published_time":"2023-04-24T11:58:39+00:00","article_modified_time":"2024-05-05T17:01:54+00:00","og_image":[{"width":964,"height":618,"url":"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2023\/04\/elodiefont.jpg","type":"image\/jpeg"}],"author":"Veronica Noseda","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Veronica Noseda","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/#article","isPartOf":{"@id":"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/"},"author":{"name":"Veronica Noseda","@id":"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec"},"headline":"&#8220;A nos d\u00e9sirs&#8221;, essai sur la sexualit\u00e9 lesbienne","datePublished":"2023-04-24T11:58:39+00:00","dateModified":"2024-05-05T17:01:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/"},"wordCount":210,"image":{"@id":"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2023\/04\/elodiefont.jpg","articleSection":["Projets soutenus"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/","url":"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/","name":"\"A nos d\u00e9sirs\", essai sur la sexualit\u00e9 lesbienne &#8212; LIG","isPartOf":{"@id":"https:\/\/www.fondslesbien.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/#primaryimage"},"image":{"@id":"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2023\/04\/elodiefont.jpg","datePublished":"2023-04-24T11:58:39+00:00","dateModified":"2024-05-05T17:01:54+00:00","author":{"@id":"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec"},"breadcrumb":{"@id":"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/#primaryimage","url":"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2023\/04\/elodiefont.jpg","contentUrl":"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2023\/04\/elodiefont.jpg","width":964,"height":618},{"@type":"BreadcrumbList","@id":"https:\/\/www.fondslesbien.org\/essai-sur-la-sexualite-lesbienne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fondslesbien.org\/"},{"@type":"ListItem","position":2,"name":"\u00ab\u00a0A nos d\u00e9sirs\u00a0\u00bb, essai sur la sexualit\u00e9 lesbienne"}]},{"@type":"WebSite","@id":"https:\/\/www.fondslesbien.org\/#website","url":"https:\/\/www.fondslesbien.org\/","name":"LIG","description":"Lesbiennes d\u2019Int\u00e9r\u00eat G\u00e9n\u00e9ral","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondslesbien.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec","name":"Veronica Noseda","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondslesbien.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/56a20513ad0e9ee8a12ca4e787476caa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56a20513ad0e9ee8a12ca4e787476caa?s=96&d=mm&r=g","caption":"Veronica Noseda"},"url":"https:\/\/www.fondslesbien.org\/en\/author\/yurilig\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/posts\/2352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/comments?post=2352"}],"version-history":[{"count":5,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/posts\/2352\/revisions"}],"predecessor-version":[{"id":2541,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/posts\/2352\/revisions\/2541"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/media\/2353"}],"wp:attachment":[{"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/media?parent=2352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/categories?post=2352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/tags?post=2352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}