{"id":2408,"date":"2023-12-21T16:51:08","date_gmt":"2023-12-21T15:51:08","guid":{"rendered":"https:\/\/www.fondslesbien.org\/?p=2408"},"modified":"2024-01-31T11:18:29","modified_gmt":"2024-01-31T10:18:29","slug":"ou-sont-les-personnages-lgbtqi","status":"publish","type":"post","link":"https:\/\/www.fondslesbien.org\/en\/ou-sont-les-personnages-lgbtqi\/","title":{"rendered":"O\u00f9 sont les personnages LGBTQI+ ?"},"content":{"rendered":"<p>A l\u2019int\u00e9rieur d\u2019une collection de guides sur les repr\u00e9sentations en litt\u00e9rature jeunesse, Spencer Robinson et Sarah<br \/>\nGhelam pr\u00e9senteront les repr\u00e9sentations disponibles de personnages LGBTQI+ au sein de la production d\u2019albums jeunesse en<br \/>\nFrance. Spencer Robinson, masterant ayant soutenu un m\u00e9moire sur les repr\u00e9sentations trans dans les albums jeunesse, sera<br \/>\nen charge des repr\u00e9sentations gay et trans, Sarah Ghelam, en pr\u00e9paration d\u2019une th\u00e8se sur les personnages enfantins non blancs<br \/>\ndans les albums jeunesse, sera en charge des repr\u00e9sentations lesbiennes et bies.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A l\u2019int\u00e9rieur d\u2019une collection de guides sur les repr\u00e9sentations en litt\u00e9rature jeunesse, Spencer Robinson et Sarah Ghelam pr\u00e9senteront les repr\u00e9sentations disponibles de personnages LGBTQI+ au sein de la production d\u2019albums jeunesse en France. Spencer Robinson, masterant ayant soutenu un m\u00e9moire sur les repr\u00e9sentations trans dans les albums jeunesse, sera en charge des repr\u00e9sentations gay et&#8230;<\/p>\n","protected":false},"author":2,"featured_media":2466,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-2408","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-projets-soutenus"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["fr","en"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O\u00f9 sont les personnages LGBTQI+ ? &#8212; LIG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O\u00f9 sont les personnages LGBTQI+ ? &#8212; LIG\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/\" \/>\n<meta property=\"og:site_name\" content=\"LIG\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-21T15:51:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-31T10:18:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2023\/12\/91bb26_4e0d99dae2ca429b8ccffea6950b298amv2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"828\" \/>\n\t<meta property=\"og:image:height\" content=\"1070\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Veronica Noseda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Veronica Noseda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/\"},\"author\":{\"name\":\"Veronica Noseda\",\"@id\":\"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec\"},\"headline\":\"O\u00f9 sont les personnages LGBTQI+ ?\",\"datePublished\":\"2023-12-21T15:51:08+00:00\",\"dateModified\":\"2024-01-31T10:18:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/\"},\"wordCount\":100,\"image\":{\"@id\":\"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2023\/12\/91bb26_4e0d99dae2ca429b8ccffea6950b298amv2.jpg\",\"articleSection\":[\"Projets soutenus\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/\",\"url\":\"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/\",\"name\":\"O\u00f9 sont les personnages LGBTQI+ ? &#8212; LIG\",\"isPartOf\":{\"@id\":\"https:\/\/www.fondslesbien.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2023\/12\/91bb26_4e0d99dae2ca429b8ccffea6950b298amv2.jpg\",\"datePublished\":\"2023-12-21T15:51:08+00:00\",\"dateModified\":\"2024-01-31T10:18:29+00:00\",\"author\":{\"@id\":\"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/#primaryimage\",\"url\":\"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2023\/12\/91bb26_4e0d99dae2ca429b8ccffea6950b298amv2.jpg\",\"contentUrl\":\"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2023\/12\/91bb26_4e0d99dae2ca429b8ccffea6950b298amv2.jpg\",\"width\":828,\"height\":1070},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fondslesbien.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O\u00f9 sont les personnages LGBTQI+ ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fondslesbien.org\/#website\",\"url\":\"https:\/\/www.fondslesbien.org\/\",\"name\":\"LIG\",\"description\":\"Lesbiennes d\u2019Int\u00e9r\u00eat G\u00e9n\u00e9ral\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fondslesbien.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec\",\"name\":\"Veronica Noseda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.fondslesbien.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/56a20513ad0e9ee8a12ca4e787476caa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/56a20513ad0e9ee8a12ca4e787476caa?s=96&d=mm&r=g\",\"caption\":\"Veronica Noseda\"},\"url\":\"https:\/\/www.fondslesbien.org\/en\/author\/yurilig\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O\u00f9 sont les personnages LGBTQI+ ? &#8212; LIG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/","og_locale":"en_US","og_type":"article","og_title":"O\u00f9 sont les personnages LGBTQI+ ? &#8212; LIG","og_url":"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/","og_site_name":"LIG","article_published_time":"2023-12-21T15:51:08+00:00","article_modified_time":"2024-01-31T10:18:29+00:00","og_image":[{"width":828,"height":1070,"url":"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2023\/12\/91bb26_4e0d99dae2ca429b8ccffea6950b298amv2.jpg","type":"image\/jpeg"}],"author":"Veronica Noseda","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Veronica Noseda","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/#article","isPartOf":{"@id":"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/"},"author":{"name":"Veronica Noseda","@id":"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec"},"headline":"O\u00f9 sont les personnages LGBTQI+ ?","datePublished":"2023-12-21T15:51:08+00:00","dateModified":"2024-01-31T10:18:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/"},"wordCount":100,"image":{"@id":"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2023\/12\/91bb26_4e0d99dae2ca429b8ccffea6950b298amv2.jpg","articleSection":["Projets soutenus"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/","url":"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/","name":"O\u00f9 sont les personnages LGBTQI+ ? &#8212; LIG","isPartOf":{"@id":"https:\/\/www.fondslesbien.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/#primaryimage"},"image":{"@id":"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2023\/12\/91bb26_4e0d99dae2ca429b8ccffea6950b298amv2.jpg","datePublished":"2023-12-21T15:51:08+00:00","dateModified":"2024-01-31T10:18:29+00:00","author":{"@id":"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec"},"breadcrumb":{"@id":"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/#primaryimage","url":"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2023\/12\/91bb26_4e0d99dae2ca429b8ccffea6950b298amv2.jpg","contentUrl":"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2023\/12\/91bb26_4e0d99dae2ca429b8ccffea6950b298amv2.jpg","width":828,"height":1070},{"@type":"BreadcrumbList","@id":"https:\/\/www.fondslesbien.org\/ou-sont-les-personnages-lgbtqi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fondslesbien.org\/"},{"@type":"ListItem","position":2,"name":"O\u00f9 sont les personnages LGBTQI+ ?"}]},{"@type":"WebSite","@id":"https:\/\/www.fondslesbien.org\/#website","url":"https:\/\/www.fondslesbien.org\/","name":"LIG","description":"Lesbiennes d\u2019Int\u00e9r\u00eat G\u00e9n\u00e9ral","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondslesbien.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec","name":"Veronica Noseda","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondslesbien.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/56a20513ad0e9ee8a12ca4e787476caa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56a20513ad0e9ee8a12ca4e787476caa?s=96&d=mm&r=g","caption":"Veronica Noseda"},"url":"https:\/\/www.fondslesbien.org\/en\/author\/yurilig\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/posts\/2408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/comments?post=2408"}],"version-history":[{"count":1,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/posts\/2408\/revisions"}],"predecessor-version":[{"id":2410,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/posts\/2408\/revisions\/2410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/media\/2466"}],"wp:attachment":[{"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/media?parent=2408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/categories?post=2408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/tags?post=2408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}