{"id":2479,"date":"2024-02-13T17:42:11","date_gmt":"2024-02-13T16:42:11","guid":{"rendered":"https:\/\/www.fondslesbien.org\/?p=2479"},"modified":"2024-12-17T14:20:32","modified_gmt":"2024-12-17T13:20:32","slug":"a-la-decouverte-des-terres-lesbiennes-du-wyoming","status":"publish","type":"post","link":"https:\/\/www.fondslesbien.org\/en\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/","title":{"rendered":"A la d\u00e9couverte des terres lesbiennes de l&#8217;Oregon"},"content":{"rendered":"<p>Les &#8220;Women&#8217;s Lands&#8221; sont au c\u0153ur d&#8217;une utopie qui anim\u00e9 la vie et le r\u00eave de dizaines de lesbiennes, en France et aux Etats-Unis. L&#8217;Etat de l&#8217;Oregon a \u00e9t\u00e9 le berceau id\u00e9al d&#8217;un grand nombre de ces terres lesbiennes, parmi lesquelles la Fly Away Home, fond\u00e9e par Madrone et Bethroot, deux femmes octog\u00e9naires, qui vivent \u00e0 l\u2019\u00e9cart de la soci\u00e9t\u00e9, dans les for\u00eats.<\/p>\n<p>La LIG est tr\u00e8s heureuse de financer un projet documentaire r\u00e9alis\u00e9 par C\u00e9cile Simon et Ana\u00efs Dupuis sur cet incroyable pan relativement m\u00e9connu de l&#8217;histoire lesbienne. Le film, de la dur\u00e9e d&#8217;une quarantaine de minutes, devrait \u00eatre finalis\u00e9 d&#8217;ici la fin 2024. Ce sera l&#8217;occasion pour revenir sur les enjeux du s\u00e9paratisme lesbien, de l&#8217;\u00e9cof\u00e9minisme et surtout sur l&#8217;envie de faire communaut\u00e9 envers et contre le patriarcat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les &#8220;Women&#8217;s Lands&#8221; sont au c\u0153ur d&#8217;une utopie qui anim\u00e9 la vie et le r\u00eave de dizaines de lesbiennes, en France et aux Etats-Unis. L&#8217;Etat de l&#8217;Oregon a \u00e9t\u00e9 le berceau id\u00e9al d&#8217;un grand nombre de ces terres lesbiennes, parmi lesquelles la Fly Away Home, fond\u00e9e par Madrone et Bethroot, deux femmes octog\u00e9naires, qui vivent&#8230;<\/p>\n","protected":false},"author":2,"featured_media":2480,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-2479","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-projets-soutenus"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["fr","en"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A la d\u00e9couverte des terres lesbiennes de l&#039;Oregon &#8212; LIG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A la d\u00e9couverte des terres lesbiennes de l&#039;Oregon &#8212; LIG\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/\" \/>\n<meta property=\"og:site_name\" content=\"LIG\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-13T16:42:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-17T13:20:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2024\/02\/wyoming-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1584\" \/>\n\t<meta property=\"og:image:height\" content=\"986\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Veronica Noseda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Veronica Noseda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/\"},\"author\":{\"name\":\"Veronica Noseda\",\"@id\":\"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec\"},\"headline\":\"A la d\u00e9couverte des terres lesbiennes de l&#8217;Oregon\",\"datePublished\":\"2024-02-13T16:42:11+00:00\",\"dateModified\":\"2024-12-17T13:20:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/\"},\"wordCount\":165,\"image\":{\"@id\":\"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2024\/02\/wyoming-2.png\",\"articleSection\":[\"Projets soutenus\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/\",\"url\":\"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/\",\"name\":\"A la d\u00e9couverte des terres lesbiennes de l'Oregon &#8212; LIG\",\"isPartOf\":{\"@id\":\"https:\/\/www.fondslesbien.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2024\/02\/wyoming-2.png\",\"datePublished\":\"2024-02-13T16:42:11+00:00\",\"dateModified\":\"2024-12-17T13:20:32+00:00\",\"author\":{\"@id\":\"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/#primaryimage\",\"url\":\"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2024\/02\/wyoming-2.png\",\"contentUrl\":\"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2024\/02\/wyoming-2.png\",\"width\":1584,\"height\":986},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fondslesbien.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A la d\u00e9couverte des terres lesbiennes de l&rsquo;Oregon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fondslesbien.org\/#website\",\"url\":\"https:\/\/www.fondslesbien.org\/\",\"name\":\"LIG\",\"description\":\"Lesbiennes d\u2019Int\u00e9r\u00eat G\u00e9n\u00e9ral\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fondslesbien.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec\",\"name\":\"Veronica Noseda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.fondslesbien.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/56a20513ad0e9ee8a12ca4e787476caa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/56a20513ad0e9ee8a12ca4e787476caa?s=96&d=mm&r=g\",\"caption\":\"Veronica Noseda\"},\"url\":\"https:\/\/www.fondslesbien.org\/en\/author\/yurilig\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A la d\u00e9couverte des terres lesbiennes de l'Oregon &#8212; LIG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/","og_locale":"en_US","og_type":"article","og_title":"A la d\u00e9couverte des terres lesbiennes de l'Oregon &#8212; LIG","og_url":"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/","og_site_name":"LIG","article_published_time":"2024-02-13T16:42:11+00:00","article_modified_time":"2024-12-17T13:20:32+00:00","og_image":[{"width":1584,"height":986,"url":"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2024\/02\/wyoming-2.png","type":"image\/png"}],"author":"Veronica Noseda","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Veronica Noseda","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/#article","isPartOf":{"@id":"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/"},"author":{"name":"Veronica Noseda","@id":"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec"},"headline":"A la d\u00e9couverte des terres lesbiennes de l&#8217;Oregon","datePublished":"2024-02-13T16:42:11+00:00","dateModified":"2024-12-17T13:20:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/"},"wordCount":165,"image":{"@id":"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2024\/02\/wyoming-2.png","articleSection":["Projets soutenus"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/","url":"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/","name":"A la d\u00e9couverte des terres lesbiennes de l'Oregon &#8212; LIG","isPartOf":{"@id":"https:\/\/www.fondslesbien.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/#primaryimage"},"image":{"@id":"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2024\/02\/wyoming-2.png","datePublished":"2024-02-13T16:42:11+00:00","dateModified":"2024-12-17T13:20:32+00:00","author":{"@id":"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec"},"breadcrumb":{"@id":"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/#primaryimage","url":"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2024\/02\/wyoming-2.png","contentUrl":"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2024\/02\/wyoming-2.png","width":1584,"height":986},{"@type":"BreadcrumbList","@id":"https:\/\/www.fondslesbien.org\/a-la-decouverte-des-terres-lesbiennes-du-wyoming\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fondslesbien.org\/"},{"@type":"ListItem","position":2,"name":"A la d\u00e9couverte des terres lesbiennes de l&rsquo;Oregon"}]},{"@type":"WebSite","@id":"https:\/\/www.fondslesbien.org\/#website","url":"https:\/\/www.fondslesbien.org\/","name":"LIG","description":"Lesbiennes d\u2019Int\u00e9r\u00eat G\u00e9n\u00e9ral","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondslesbien.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec","name":"Veronica Noseda","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondslesbien.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/56a20513ad0e9ee8a12ca4e787476caa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56a20513ad0e9ee8a12ca4e787476caa?s=96&d=mm&r=g","caption":"Veronica Noseda"},"url":"https:\/\/www.fondslesbien.org\/en\/author\/yurilig\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/posts\/2479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/comments?post=2479"}],"version-history":[{"count":5,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/posts\/2479\/revisions"}],"predecessor-version":[{"id":2483,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/posts\/2479\/revisions\/2483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/media\/2480"}],"wp:attachment":[{"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/media?parent=2479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/categories?post=2479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/tags?post=2479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}