{"id":2603,"date":"2024-12-17T19:18:50","date_gmt":"2024-12-17T18:18:50","guid":{"rendered":"https:\/\/www.fondslesbien.org\/?p=2603"},"modified":"2024-12-17T19:18:50","modified_gmt":"2024-12-17T18:18:50","slug":"dou-ca-gronde-performance-de-dalidyke","status":"publish","type":"post","link":"https:\/\/www.fondslesbien.org\/en\/dou-ca-gronde-performance-de-dalidyke\/","title":{"rendered":"&#8220;D&#8217;o\u00f9 \u00e7a gronde&#8221; &#8211; performance de Dalidyke"},"content":{"rendered":"<p>\u00ab D\u2019O\u00d9 \u00c7A GRONDE \u00bb une pi\u00e8ce sous forme de solo de RAP performatif \u00e9rotico-col\u00e9ro-dramatique, dont Jo\u00e9 LOPES assure l\u2019\u00e9criture, le jeu et la mise en sc\u00e8ne, avec la collaboration artistique de Fanny SINT\u00c8S sur la mise en sc\u00e8ne.<br \/>\nCom\u00e9dien\u00b7ne, auteur\u00b7rice et performeur\u00b7euse, Jo\u00e9 LOPES utilise son parcours, sa trajectoire, sa voix, son cri, dans des chants incarn\u00e9s par tout son corps.<br \/>\nC&#8217;est un r\u00e9cit de l\u2019intime fait de chemins de traverse, avec ses outils que sont le RAP, le chant et le jeu th\u00e9\u00e2tral, avec une adresse directe tendre et empathique \u00e0 son public.<br \/>\nBad bitch dans un style non poliss\u00e9 et sans faux-semblant, des ongles longs et pointus, une langue aff\u00fbt\u00e9e et ruisselante, Jo\u00e9 LOPES utilise sa forme de langage, son style, vrai, po\u00e9tique et percutant, et ses constructions pour \u00e9tendre ce qui part de l&#8217;intimit\u00e9 et qui devient politique quand on le partage avec d\u2019autres, que l\u2019on cr\u00e9e du commun, de la reconnaissance de soi et des autres.<br \/>\nUn r\u00e9cit de soi autour des questions de classe, de race et de genre, qui consid\u00e8re le parcours de vie comme de la mati\u00e8re \u00e0 cr\u00e9er, \u00e0 partager, \u00e0 sublimer, \u00e0 transcender, \u00e0 assumer. Des histoires aux identit\u00e9s multiples et singuli\u00e8res, non calibr\u00e9es, non norm\u00e9es.<br \/>\nUne vie pleine de trajectoires, de parcours de violence, d\u2019humour grin\u00e7ant et de po\u00e9sie, de transformation, d\u2019hybridit\u00e9 et d\u2019amour.<br \/>\nCette cr\u00e9ation est port\u00e9e par la Compagnie Pendant que les champs br\u00fblent, cr\u00e9\u00e9e par Jo\u00e9 LOPES en 2023, qui se veut de consid\u00e9rer le parcours, les trajectoires de vie, comme un point de d\u00e9part, un socle, une base, comme moteur \u00e0 la cr\u00e9ation pour transcender et sublimer nos r\u00e9alit\u00e9s. Les assumer et \u00eatre fi\u00e8r\u00b7e de nos existences. R\u00e9inventer nos identit\u00e9s, sortir des stigmates ou en \u00eatre conscient\u00b7e pour jouer avec, et s\u2019en servir dans une pens\u00e9e intersectionnelle et queer. Trouver l\u2019humour au bon endroit, \u00e0 l\u2019endroit juste, pour jouer des codes sur un terrain de jeu avec ses propres r\u00e8gles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab D\u2019O\u00d9 \u00c7A GRONDE \u00bb une pi\u00e8ce sous forme de solo de RAP performatif \u00e9rotico-col\u00e9ro-dramatique, dont Jo\u00e9 LOPES assure l\u2019\u00e9criture, le jeu et la mise en sc\u00e8ne, avec la collaboration artistique de Fanny SINT\u00c8S sur la mise en sc\u00e8ne. Com\u00e9dien\u00b7ne, auteur\u00b7rice et performeur\u00b7euse, Jo\u00e9 LOPES utilise son parcours, sa trajectoire, sa voix, son cri, dans&#8230;<\/p>\n","protected":false},"author":2,"featured_media":2605,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-2603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-projets-soutenus"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["fr","en"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;D&#039;o\u00f9 \u00e7a gronde&quot; - performance de Dalidyke &#8212; LIG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;D&#039;o\u00f9 \u00e7a gronde&quot; - performance de Dalidyke &#8212; LIG\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/\" \/>\n<meta property=\"og:site_name\" content=\"LIG\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-17T18:18:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2024\/12\/dalidyke.png\" \/>\n\t<meta property=\"og:image:width\" content=\"459\" \/>\n\t<meta property=\"og:image:height\" content=\"456\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Veronica Noseda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Veronica Noseda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/\"},\"author\":{\"name\":\"Veronica Noseda\",\"@id\":\"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec\"},\"headline\":\"&#8220;D&#8217;o\u00f9 \u00e7a gronde&#8221; &#8211; performance de Dalidyke\",\"datePublished\":\"2024-12-17T18:18:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/\"},\"wordCount\":377,\"image\":{\"@id\":\"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2024\/12\/dalidyke.png\",\"articleSection\":[\"Projets soutenus\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/\",\"url\":\"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/\",\"name\":\"\\\"D'o\u00f9 \u00e7a gronde\\\" - performance de Dalidyke &#8212; LIG\",\"isPartOf\":{\"@id\":\"https:\/\/www.fondslesbien.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2024\/12\/dalidyke.png\",\"datePublished\":\"2024-12-17T18:18:50+00:00\",\"author\":{\"@id\":\"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/#primaryimage\",\"url\":\"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2024\/12\/dalidyke.png\",\"contentUrl\":\"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2024\/12\/dalidyke.png\",\"width\":459,\"height\":456},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fondslesbien.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab\u00a0D&rsquo;o\u00f9 \u00e7a gronde\u00a0\u00bb &#8211; performance de Dalidyke\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fondslesbien.org\/#website\",\"url\":\"https:\/\/www.fondslesbien.org\/\",\"name\":\"LIG\",\"description\":\"Lesbiennes d\u2019Int\u00e9r\u00eat G\u00e9n\u00e9ral\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fondslesbien.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec\",\"name\":\"Veronica Noseda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.fondslesbien.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/56a20513ad0e9ee8a12ca4e787476caa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/56a20513ad0e9ee8a12ca4e787476caa?s=96&d=mm&r=g\",\"caption\":\"Veronica Noseda\"},\"url\":\"https:\/\/www.fondslesbien.org\/en\/author\/yurilig\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"D'o\u00f9 \u00e7a gronde\" - performance de Dalidyke &#8212; LIG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/","og_locale":"en_US","og_type":"article","og_title":"\"D'o\u00f9 \u00e7a gronde\" - performance de Dalidyke &#8212; LIG","og_url":"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/","og_site_name":"LIG","article_published_time":"2024-12-17T18:18:50+00:00","og_image":[{"width":459,"height":456,"url":"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2024\/12\/dalidyke.png","type":"image\/png"}],"author":"Veronica Noseda","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Veronica Noseda","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/#article","isPartOf":{"@id":"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/"},"author":{"name":"Veronica Noseda","@id":"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec"},"headline":"&#8220;D&#8217;o\u00f9 \u00e7a gronde&#8221; &#8211; performance de Dalidyke","datePublished":"2024-12-17T18:18:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/"},"wordCount":377,"image":{"@id":"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2024\/12\/dalidyke.png","articleSection":["Projets soutenus"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/","url":"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/","name":"\"D'o\u00f9 \u00e7a gronde\" - performance de Dalidyke &#8212; LIG","isPartOf":{"@id":"https:\/\/www.fondslesbien.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/#primaryimage"},"image":{"@id":"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2024\/12\/dalidyke.png","datePublished":"2024-12-17T18:18:50+00:00","author":{"@id":"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec"},"breadcrumb":{"@id":"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/#primaryimage","url":"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2024\/12\/dalidyke.png","contentUrl":"https:\/\/www.fondslesbien.org\/wp-content\/uploads\/2024\/12\/dalidyke.png","width":459,"height":456},{"@type":"BreadcrumbList","@id":"https:\/\/www.fondslesbien.org\/dou-ca-gronde-performance-de-dalidyke\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fondslesbien.org\/"},{"@type":"ListItem","position":2,"name":"\u00ab\u00a0D&rsquo;o\u00f9 \u00e7a gronde\u00a0\u00bb &#8211; performance de Dalidyke"}]},{"@type":"WebSite","@id":"https:\/\/www.fondslesbien.org\/#website","url":"https:\/\/www.fondslesbien.org\/","name":"LIG","description":"Lesbiennes d\u2019Int\u00e9r\u00eat G\u00e9n\u00e9ral","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondslesbien.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.fondslesbien.org\/#\/schema\/person\/9ab55cc49715d7721bb788dbd52174ec","name":"Veronica Noseda","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fondslesbien.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/56a20513ad0e9ee8a12ca4e787476caa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56a20513ad0e9ee8a12ca4e787476caa?s=96&d=mm&r=g","caption":"Veronica Noseda"},"url":"https:\/\/www.fondslesbien.org\/en\/author\/yurilig\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/posts\/2603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/comments?post=2603"}],"version-history":[{"count":3,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/posts\/2603\/revisions"}],"predecessor-version":[{"id":2607,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/posts\/2603\/revisions\/2607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/media\/2605"}],"wp:attachment":[{"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/media?parent=2603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/categories?post=2603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fondslesbien.org\/en\/wp-json\/wp\/v2\/tags?post=2603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}